{"id":750,"date":"2024-05-31T15:37:01","date_gmt":"2024-05-31T15:37:01","guid":{"rendered":"https:\/\/missionsencounter.com\/?page_id=750"},"modified":"2026-03-24T21:41:30","modified_gmt":"2026-03-24T21:41:30","slug":"missions-encounter-youth","status":"publish","type":"page","link":"https:\/\/missionsencounter.com\/index.php\/missions-encounter-youth\/","title":{"rendered":"Missions Encounter Youth"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Header&#8221; _builder_version=&#8221;4.25.1&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(0,12,36,0.8) 0%|rgba(0,12,36,0) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;http:\/\/missionsencounter.com\/wp-content\/uploads\/2024\/05\/missions-encounter-youth-1.jpg&#8221; background_position=&#8221;top_center&#8221; custom_padding=&#8221;1vw||4vw||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; background_color_gradient_start__hover=&#8221;#2b87da&#8221; background_color_gradient_start__hover_enabled=&#8221;#2b87da&#8221; background_color_gradient_end__hover=&#8221;#29c4a9&#8243; background_color_gradient_end__hover_enabled=&#8221;#29c4a9&#8243; use_background_color_gradient__hover=&#8221;off&#8221; use_background_color_gradient__hover_enabled=&#8221;off&#8221; background_color_gradient_type__hover=&#8221;linear&#8221; background_color_gradient_type__hover_enabled=&#8221;linear&#8221; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_direction_radial__hover=&#8221;center&#8221; background_color_gradient_direction_radial__hover_enabled=&#8221;center&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; background_color_gradient_overlays_image__hover=&#8221;off&#8221; background_color_gradient_overlays_image__hover_enabled=&#8221;off&#8221; background_color_gradient_stops__hover=&#8221;#2b87da 0%|#29c4a9 100%&#8221;][et_pb_row _builder_version=&#8221;4.18.0&#8243; max_width=&#8221;80%&#8221; min_height=&#8221;135.1px&#8221; custom_margin=&#8221;0px|auto||auto|false|false&#8221; custom_padding=&#8221;0px|||||&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_px__hover=&#8221;1080px&#8221; custom_width_px__hover_enabled=&#8221;1080px&#8221; custom_width_percent__hover=&#8221;80%&#8221; custom_width_percent__hover_enabled=&#8221;80%&#8221; global_colors_info=&#8221;{}&#8221; gutter_width__hover=&#8221;3&#8243; gutter_width__hover_enabled=&#8221;3&#8243; parallax_1__hover=&#8221;off&#8221; parallax_1__hover_enabled=&#8221;off&#8221; parallax_2__hover=&#8221;off&#8221; parallax_2__hover_enabled=&#8221;off&#8221; parallax_3__hover=&#8221;off&#8221; parallax_3__hover_enabled=&#8221;off&#8221; parallax_4__hover=&#8221;off&#8221; parallax_4__hover_enabled=&#8221;off&#8221; parallax_5__hover=&#8221;off&#8221; parallax_5__hover_enabled=&#8221;off&#8221; parallax_6__hover=&#8221;off&#8221; parallax_6__hover_enabled=&#8221;off&#8221; parallax_method_1__hover=&#8221;on&#8221; parallax_method_1__hover_enabled=&#8221;on&#8221; parallax_method_2__hover=&#8221;on&#8221; parallax_method_2__hover_enabled=&#8221;on&#8221; parallax_method_3__hover=&#8221;on&#8221; parallax_method_3__hover_enabled=&#8221;on&#8221; parallax_method_4__hover=&#8221;on&#8221; parallax_method_4__hover_enabled=&#8221;on&#8221; parallax_method_5__hover=&#8221;on&#8221; parallax_method_5__hover_enabled=&#8221;on&#8221; parallax_method_6__hover=&#8221;on&#8221; parallax_method_6__hover_enabled=&#8221;on&#8221; use_background_color_gradient__hover=&#8221;off&#8221; use_background_color_gradient__hover_enabled=&#8221;off&#8221; background_color_gradient_start__hover=&#8221;#2b87da&#8221; background_color_gradient_start__hover_enabled=&#8221;#2b87da&#8221; background_color_gradient_end__hover=&#8221;#29c4a9&#8243; background_color_gradient_end__hover_enabled=&#8221;#29c4a9&#8243; background_color_gradient_type__hover=&#8221;linear&#8221; background_color_gradient_type__hover_enabled=&#8221;linear&#8221; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_direction_radial__hover=&#8221;center&#8221; background_color_gradient_direction_radial__hover_enabled=&#8221;center&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; background_color_gradient_overlays_image__hover=&#8221;off&#8221; background_color_gradient_overlays_image__hover_enabled=&#8221;off&#8221; parallax__hover=&#8221;off&#8221; parallax__hover_enabled=&#8221;off&#8221; parallax_method__hover=&#8221;on&#8221; parallax_method__hover_enabled=&#8221;on&#8221; background_size__hover=&#8221;cover&#8221; background_size__hover_enabled=&#8221;cover&#8221; background_position__hover=&#8221;center&#8221; background_position__hover_enabled=&#8221;center&#8221; background_repeat__hover=&#8221;no-repeat&#8221; background_repeat__hover_enabled=&#8221;no-repeat&#8221; background_blend__hover=&#8221;normal&#8221; background_blend__hover_enabled=&#8221;normal&#8221; allow_player_pause__hover=&#8221;off&#8221; allow_player_pause__hover_enabled=&#8221;off&#8221; background_video_pause_outside_viewport__hover=&#8221;on&#8221; background_video_pause_outside_viewport__hover_enabled=&#8221;on&#8221; make_fullwidth__hover=&#8221;off&#8221; make_fullwidth__hover_enabled=&#8221;off&#8221; use_custom_width__hover=&#8221;off&#8221; use_custom_width__hover_enabled=&#8221;off&#8221; width_unit__hover=&#8221;on&#8221; width_unit__hover_enabled=&#8221;on&#8221; use_custom_gutter__hover=&#8221;off&#8221; use_custom_gutter__hover_enabled=&#8221;off&#8221; make_equal__hover=&#8221;off&#8221; make_equal__hover_enabled=&#8221;off&#8221; border_radii__hover=&#8221;on||||&#8221; border_radii__hover_enabled=&#8221;on||||&#8221; box_shadow_style__hover=&#8221;none&#8221; box_shadow_style__hover_enabled=&#8221;none&#8221; box_shadow_color__hover=&#8221;rgba(0,0,0,0.3)&#8221; box_shadow_color__hover_enabled=&#8221;rgba(0,0,0,0.3)&#8221; filter_hue_rotate__hover=&#8221;0deg&#8221; filter_hue_rotate__hover_enabled=&#8221;0deg&#8221; filter_saturate__hover=&#8221;100%&#8221; filter_saturate__hover_enabled=&#8221;100%&#8221; filter_brightness__hover=&#8221;100%&#8221; filter_brightness__hover_enabled=&#8221;100%&#8221; filter_contrast__hover=&#8221;100%&#8221; filter_contrast__hover_enabled=&#8221;100%&#8221; filter_invert__hover=&#8221;0%&#8221; filter_invert__hover_enabled=&#8221;0%&#8221; filter_sepia__hover=&#8221;0%&#8221; filter_sepia__hover_enabled=&#8221;0%&#8221; filter_opacity__hover=&#8221;100%&#8221; filter_opacity__hover_enabled=&#8221;100%&#8221; filter_blur__hover=&#8221;0px&#8221; filter_blur__hover_enabled=&#8221;0px&#8221; mix_blend_mode__hover=&#8221;normal&#8221; mix_blend_mode__hover_enabled=&#8221;normal&#8221; animation_style__hover=&#8221;none&#8221; animation_style__hover_enabled=&#8221;none&#8221; animation_repeat__hover=&#8221;once&#8221; animation_repeat__hover_enabled=&#8221;once&#8221; animation_direction__hover=&#8221;center&#8221; animation_direction__hover_enabled=&#8221;center&#8221; animation_duration__hover=&#8221;1000ms&#8221; animation_duration__hover_enabled=&#8221;1000ms&#8221; animation_delay__hover=&#8221;0ms&#8221; animation_delay__hover_enabled=&#8221;0ms&#8221; animation_intensity_slide__hover=&#8221;50%&#8221; animation_intensity_slide__hover_enabled=&#8221;50%&#8221; animation_intensity_zoom__hover=&#8221;50%&#8221; animation_intensity_zoom__hover_enabled=&#8221;50%&#8221; animation_intensity_flip__hover=&#8221;50%&#8221; animation_intensity_flip__hover_enabled=&#8221;50%&#8221; animation_intensity_fold__hover=&#8221;50%&#8221; animation_intensity_fold__hover_enabled=&#8221;50%&#8221; animation_intensity_roll__hover=&#8221;50%&#8221; animation_intensity_roll__hover_enabled=&#8221;50%&#8221; animation_starting_opacity__hover=&#8221;0%&#8221; animation_starting_opacity__hover_enabled=&#8221;0%&#8221; animation_speed_curve__hover=&#8221;ease-in-out&#8221; animation_speed_curve__hover_enabled=&#8221;ease-in-out&#8221; hover_transition_duration__hover=&#8221;300ms&#8221; hover_transition_duration__hover_enabled=&#8221;300ms&#8221; hover_transition_delay__hover=&#8221;0ms&#8221; hover_transition_delay__hover_enabled=&#8221;0ms&#8221; hover_transition_speed_curve__hover=&#8221;ease&#8221; hover_transition_speed_curve__hover_enabled=&#8221;ease&#8221; width__hover=&#8221;80%&#8221; width__hover_enabled=&#8221;80%&#8221; max_width__hover=&#8221;80%&#8221; max_width__hover_enabled=&#8221;80%&#8221; background_color_gradient_stops__hover=&#8221;#2b87da 0%|#29c4a9 100%&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;Noto Serif||||||||&#8221; header_font_size=&#8221;3vw&#8221; header_line_height=&#8221;1.2em&#8221; header_2_font=&#8221;||||||||&#8221; header_5_font=&#8221;||||||||&#8221; header_6_font=&#8221;Source Sans Pro|||on|||||&#8221; header_6_font_size=&#8221;24px&#8221; header_6_letter_spacing=&#8221;8px&#8221; header_6_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; max_width=&#8221;60%&#8221; max_width_tablet=&#8221;&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px||0px|||&#8221; custom_padding=&#8221;50px||50px||false|false&#8221; animation_style=&#8221;slide&#8221; animation_intensity_slide=&#8221;4%&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;48px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_text_shadow_style=&#8221;preset3&#8243; header_text_shadow_blur_strength=&#8221;0.8em&#8221; header_text_shadow_color=&#8221;rgba(0,17,51,0.55)&#8221; global_colors_info=&#8221;{}&#8221; text_font_size__hover=&#8221;14px&#8221; text_font_size__hover_enabled=&#8221;14px&#8221; text_letter_spacing__hover=&#8221;0px&#8221; text_letter_spacing__hover_enabled=&#8221;0px&#8221; text_line_height__hover=&#8221;1.7em&#8221; text_line_height__hover_enabled=&#8221;1.7em&#8221; text_text_shadow_style__hover=&#8221;none&#8221; text_text_shadow_style__hover_enabled=&#8221;none&#8221; text_text_shadow_color__hover=&#8221;rgba(0,0,0,0.4)&#8221; text_text_shadow_color__hover_enabled=&#8221;rgba(0,0,0,0.4)&#8221; link_font_size__hover=&#8221;14px&#8221; link_font_size__hover_enabled=&#8221;14px&#8221; link_letter_spacing__hover=&#8221;0px&#8221; link_letter_spacing__hover_enabled=&#8221;0px&#8221; link_line_height__hover=&#8221;1em&#8221; link_line_height__hover_enabled=&#8221;1em&#8221; link_text_shadow_style__hover=&#8221;none&#8221; link_text_shadow_style__hover_enabled=&#8221;none&#8221; link_text_shadow_color__hover=&#8221;rgba(0,0,0,0.4)&#8221; link_text_shadow_color__hover_enabled=&#8221;rgba(0,0,0,0.4)&#8221; ul_font_size__hover=&#8221;14px&#8221; ul_font_size__hover_enabled=&#8221;14px&#8221; ul_letter_spacing__hover=&#8221;0px&#8221; ul_letter_spacing__hover_enabled=&#8221;0px&#8221; ul_line_height__hover=&#8221;1em&#8221; ul_line_height__hover_enabled=&#8221;1em&#8221; ul_text_shadow_style__hover=&#8221;none&#8221; ul_text_shadow_style__hover_enabled=&#8221;none&#8221; ul_text_shadow_color__hover=&#8221;rgba(0,0,0,0.4)&#8221; ul_text_shadow_color__hover_enabled=&#8221;rgba(0,0,0,0.4)&#8221; ol_font_size__hover=&#8221;14px&#8221; ol_font_size__hover_enabled=&#8221;14px&#8221; ol_letter_spacing__hover=&#8221;0px&#8221; ol_letter_spacing__hover_enabled=&#8221;0px&#8221; ol_line_height__hover=&#8221;1em&#8221; ol_line_height__hover_enabled=&#8221;1em&#8221; ol_text_shadow_style__hover=&#8221;none&#8221; ol_text_shadow_style__hover_enabled=&#8221;none&#8221; ol_text_shadow_color__hover=&#8221;rgba(0,0,0,0.4)&#8221; ol_text_shadow_color__hover_enabled=&#8221;rgba(0,0,0,0.4)&#8221; quote_font_size__hover=&#8221;14px&#8221; quote_font_size__hover_enabled=&#8221;14px&#8221; quote_letter_spacing__hover=&#8221;0px&#8221; quote_letter_spacing__hover_enabled=&#8221;0px&#8221; quote_line_height__hover=&#8221;1em&#8221; quote_line_height__hover_enabled=&#8221;1em&#8221; quote_text_shadow_style__hover=&#8221;none&#8221; quote_text_shadow_style__hover_enabled=&#8221;none&#8221; quote_text_shadow_color__hover=&#8221;rgba(0,0,0,0.4)&#8221; quote_text_shadow_color__hover_enabled=&#8221;rgba(0,0,0,0.4)&#8221; text_orientation__hover=&#8221;left&#8221; text_orientation__hover_enabled=&#8221;left&#8221; background_layout__hover=&#8221;light&#8221; background_layout__hover_enabled=&#8221;light&#8221;]<\/p>\n<h1>Youth Engaged in Missions<\/h1>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Monthly Meetings&#8221; _builder_version=&#8221;4.18.0&#8243; custom_width_px__hover=&#8221;1080px&#8221; custom_width_px__hover_enabled=&#8221;1080px&#8221; custom_width_percent__hover=&#8221;80%&#8221; custom_width_percent__hover_enabled=&#8221;80%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; gutter_width__hover=&#8221;3&#8243; gutter_width__hover_enabled=&#8221;3&#8243; parallax_1__hover=&#8221;off&#8221; parallax_1__hover_enabled=&#8221;off&#8221; parallax_2__hover=&#8221;off&#8221; parallax_2__hover_enabled=&#8221;off&#8221; parallax_3__hover=&#8221;off&#8221; parallax_3__hover_enabled=&#8221;off&#8221; parallax_method_1__hover=&#8221;on&#8221; parallax_method_1__hover_enabled=&#8221;on&#8221; parallax_method_2__hover=&#8221;on&#8221; parallax_method_2__hover_enabled=&#8221;on&#8221; parallax_method_3__hover=&#8221;on&#8221; parallax_method_3__hover_enabled=&#8221;on&#8221; use_background_color_gradient__hover=&#8221;off&#8221; use_background_color_gradient__hover_enabled=&#8221;off&#8221; background_color_gradient_start__hover=&#8221;#2b87da&#8221; background_color_gradient_start__hover_enabled=&#8221;#2b87da&#8221; background_color_gradient_end__hover=&#8221;#29c4a9&#8243; background_color_gradient_end__hover_enabled=&#8221;#29c4a9&#8243; background_color_gradient_type__hover=&#8221;linear&#8221; background_color_gradient_type__hover_enabled=&#8221;linear&#8221; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_direction_radial__hover=&#8221;center&#8221; background_color_gradient_direction_radial__hover_enabled=&#8221;center&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; background_color_gradient_overlays_image__hover=&#8221;off&#8221; background_color_gradient_overlays_image__hover_enabled=&#8221;off&#8221; parallax__hover=&#8221;off&#8221; parallax__hover_enabled=&#8221;off&#8221; parallax_method__hover=&#8221;on&#8221; parallax_method__hover_enabled=&#8221;on&#8221; background_size__hover=&#8221;cover&#8221; background_size__hover_enabled=&#8221;cover&#8221; background_position__hover=&#8221;center&#8221; background_position__hover_enabled=&#8221;center&#8221; background_repeat__hover=&#8221;no-repeat&#8221; background_repeat__hover_enabled=&#8221;no-repeat&#8221; background_blend__hover=&#8221;normal&#8221; background_blend__hover_enabled=&#8221;normal&#8221; allow_player_pause__hover=&#8221;off&#8221; allow_player_pause__hover_enabled=&#8221;off&#8221; background_video_pause_outside_viewport__hover=&#8221;on&#8221; background_video_pause_outside_viewport__hover_enabled=&#8221;on&#8221; inner_shadow__hover=&#8221;off&#8221; inner_shadow__hover_enabled=&#8221;off&#8221; make_fullwidth__hover=&#8221;off&#8221; make_fullwidth__hover_enabled=&#8221;off&#8221; use_custom_width__hover=&#8221;off&#8221; use_custom_width__hover_enabled=&#8221;off&#8221; width_unit__hover=&#8221;on&#8221; width_unit__hover_enabled=&#8221;on&#8221; make_equal__hover=&#8221;off&#8221; make_equal__hover_enabled=&#8221;off&#8221; use_custom_gutter__hover=&#8221;off&#8221; use_custom_gutter__hover_enabled=&#8221;off&#8221; border_radii__hover=&#8221;on||||&#8221; border_radii__hover_enabled=&#8221;on||||&#8221; box_shadow_style__hover=&#8221;none&#8221; box_shadow_style__hover_enabled=&#8221;none&#8221; box_shadow_color__hover=&#8221;rgba(0,0,0,0.3)&#8221; box_shadow_color__hover_enabled=&#8221;rgba(0,0,0,0.3)&#8221; max_width__hover=&#8221;100%&#8221; max_width__hover_enabled=&#8221;100%&#8221; filter_hue_rotate__hover=&#8221;0deg&#8221; filter_hue_rotate__hover_enabled=&#8221;0deg&#8221; filter_saturate__hover=&#8221;100%&#8221; filter_saturate__hover_enabled=&#8221;100%&#8221; filter_brightness__hover=&#8221;100%&#8221; filter_brightness__hover_enabled=&#8221;100%&#8221; filter_contrast__hover=&#8221;100%&#8221; filter_contrast__hover_enabled=&#8221;100%&#8221; filter_invert__hover=&#8221;0%&#8221; filter_invert__hover_enabled=&#8221;0%&#8221; filter_sepia__hover=&#8221;0%&#8221; filter_sepia__hover_enabled=&#8221;0%&#8221; filter_opacity__hover=&#8221;100%&#8221; filter_opacity__hover_enabled=&#8221;100%&#8221; filter_blur__hover=&#8221;0px&#8221; filter_blur__hover_enabled=&#8221;0px&#8221; mix_blend_mode__hover=&#8221;normal&#8221; mix_blend_mode__hover_enabled=&#8221;normal&#8221; animation_style__hover=&#8221;none&#8221; animation_style__hover_enabled=&#8221;none&#8221; animation_repeat__hover=&#8221;once&#8221; animation_repeat__hover_enabled=&#8221;once&#8221; animation_direction__hover=&#8221;center&#8221; animation_direction__hover_enabled=&#8221;center&#8221; animation_duration__hover=&#8221;1000ms&#8221; animation_duration__hover_enabled=&#8221;1000ms&#8221; animation_delay__hover=&#8221;0ms&#8221; animation_delay__hover_enabled=&#8221;0ms&#8221; animation_intensity_slide__hover=&#8221;50%&#8221; animation_intensity_slide__hover_enabled=&#8221;50%&#8221; animation_intensity_zoom__hover=&#8221;50%&#8221; animation_intensity_zoom__hover_enabled=&#8221;50%&#8221; animation_intensity_flip__hover=&#8221;50%&#8221; animation_intensity_flip__hover_enabled=&#8221;50%&#8221; animation_intensity_fold__hover=&#8221;50%&#8221; animation_intensity_fold__hover_enabled=&#8221;50%&#8221; animation_intensity_roll__hover=&#8221;50%&#8221; animation_intensity_roll__hover_enabled=&#8221;50%&#8221; animation_starting_opacity__hover=&#8221;0%&#8221; animation_starting_opacity__hover_enabled=&#8221;0%&#8221; animation_speed_curve__hover=&#8221;ease-in-out&#8221; animation_speed_curve__hover_enabled=&#8221;ease-in-out&#8221; hover_transition_duration__hover=&#8221;300ms&#8221; hover_transition_duration__hover_enabled=&#8221;300ms&#8221; hover_transition_delay__hover=&#8221;0ms&#8221; hover_transition_delay__hover_enabled=&#8221;0ms&#8221; hover_transition_speed_curve__hover=&#8221;ease&#8221; hover_transition_speed_curve__hover_enabled=&#8221;ease&#8221; background_color_gradient_stops__hover=&#8221;#2b87da 0%|#29c4a9 100%&#8221;][et_pb_row column_structure=&#8221;2_3,1_3&#8243; _builder_version=&#8221;4.25.1&#8243; width=&#8221;90%&#8221; min_height=&#8221;495.6px&#8221; custom_margin=&#8221;11px|auto||auto||&#8221; custom_padding=&#8221;||6px|||&#8221; border_width_right=&#8221;2px&#8221; border_color_right=&#8221;#FFFFFF&#8221; custom_width_px__hover=&#8221;1080px&#8221; custom_width_px__hover_enabled=&#8221;1080px&#8221; custom_width_percent__hover=&#8221;80%&#8221; custom_width_percent__hover_enabled=&#8221;80%&#8221; global_colors_info=&#8221;{}&#8221; use_custom_width__hover=&#8221;off&#8221; use_custom_width__hover_enabled=&#8221;off&#8221; width_unit__hover=&#8221;on&#8221; width_unit__hover_enabled=&#8221;on&#8221; gutter_width__hover=&#8221;3&#8243; gutter_width__hover_enabled=&#8221;3&#8243; parallax_1__hover=&#8221;off&#8221; parallax_1__hover_enabled=&#8221;off&#8221; parallax_2__hover=&#8221;off&#8221; parallax_2__hover_enabled=&#8221;off&#8221; parallax_3__hover=&#8221;off&#8221; parallax_3__hover_enabled=&#8221;off&#8221; parallax_4__hover=&#8221;off&#8221; parallax_4__hover_enabled=&#8221;off&#8221; parallax_5__hover=&#8221;off&#8221; parallax_5__hover_enabled=&#8221;off&#8221; parallax_6__hover=&#8221;off&#8221; parallax_6__hover_enabled=&#8221;off&#8221; parallax_method_1__hover=&#8221;on&#8221; parallax_method_1__hover_enabled=&#8221;on&#8221; parallax_method_2__hover=&#8221;on&#8221; parallax_method_2__hover_enabled=&#8221;on&#8221; parallax_method_3__hover=&#8221;on&#8221; parallax_method_3__hover_enabled=&#8221;on&#8221; parallax_method_4__hover=&#8221;on&#8221; parallax_method_4__hover_enabled=&#8221;on&#8221; parallax_method_5__hover=&#8221;on&#8221; parallax_method_5__hover_enabled=&#8221;on&#8221; parallax_method_6__hover=&#8221;on&#8221; parallax_method_6__hover_enabled=&#8221;on&#8221; use_background_color_gradient__hover=&#8221;off&#8221; use_background_color_gradient__hover_enabled=&#8221;off&#8221; background_color_gradient_start__hover=&#8221;#2b87da&#8221; background_color_gradient_start__hover_enabled=&#8221;#2b87da&#8221; background_color_gradient_end__hover=&#8221;#29c4a9&#8243; background_color_gradient_end__hover_enabled=&#8221;#29c4a9&#8243; background_color_gradient_type__hover=&#8221;linear&#8221; background_color_gradient_type__hover_enabled=&#8221;linear&#8221; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_direction_radial__hover=&#8221;center&#8221; background_color_gradient_direction_radial__hover_enabled=&#8221;center&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; background_color_gradient_overlays_image__hover=&#8221;off&#8221; background_color_gradient_overlays_image__hover_enabled=&#8221;off&#8221; parallax__hover=&#8221;off&#8221; parallax__hover_enabled=&#8221;off&#8221; parallax_method__hover=&#8221;on&#8221; parallax_method__hover_enabled=&#8221;on&#8221; background_size__hover=&#8221;cover&#8221; background_size__hover_enabled=&#8221;cover&#8221; background_position__hover=&#8221;center&#8221; background_position__hover_enabled=&#8221;center&#8221; background_repeat__hover=&#8221;no-repeat&#8221; background_repeat__hover_enabled=&#8221;no-repeat&#8221; background_blend__hover=&#8221;normal&#8221; background_blend__hover_enabled=&#8221;normal&#8221; allow_player_pause__hover=&#8221;off&#8221; allow_player_pause__hover_enabled=&#8221;off&#8221; background_video_pause_outside_viewport__hover=&#8221;on&#8221; background_video_pause_outside_viewport__hover_enabled=&#8221;on&#8221; make_fullwidth__hover=&#8221;off&#8221; make_fullwidth__hover_enabled=&#8221;off&#8221; use_custom_gutter__hover=&#8221;off&#8221; use_custom_gutter__hover_enabled=&#8221;off&#8221; make_equal__hover=&#8221;off&#8221; make_equal__hover_enabled=&#8221;off&#8221; border_radii__hover=&#8221;on||||&#8221; border_radii__hover_enabled=&#8221;on||||&#8221; box_shadow_style__hover=&#8221;none&#8221; box_shadow_style__hover_enabled=&#8221;none&#8221; box_shadow_color__hover=&#8221;rgba(0,0,0,0.3)&#8221; box_shadow_color__hover_enabled=&#8221;rgba(0,0,0,0.3)&#8221; filter_hue_rotate__hover=&#8221;0deg&#8221; filter_hue_rotate__hover_enabled=&#8221;0deg&#8221; filter_saturate__hover=&#8221;100%&#8221; filter_saturate__hover_enabled=&#8221;100%&#8221; filter_brightness__hover=&#8221;100%&#8221; filter_brightness__hover_enabled=&#8221;100%&#8221; filter_contrast__hover=&#8221;100%&#8221; filter_contrast__hover_enabled=&#8221;100%&#8221; filter_invert__hover=&#8221;0%&#8221; filter_invert__hover_enabled=&#8221;0%&#8221; filter_sepia__hover=&#8221;0%&#8221; filter_sepia__hover_enabled=&#8221;0%&#8221; filter_opacity__hover=&#8221;100%&#8221; filter_opacity__hover_enabled=&#8221;100%&#8221; filter_blur__hover=&#8221;0px&#8221; filter_blur__hover_enabled=&#8221;0px&#8221; mix_blend_mode__hover=&#8221;normal&#8221; mix_blend_mode__hover_enabled=&#8221;normal&#8221; animation_style__hover=&#8221;none&#8221; animation_style__hover_enabled=&#8221;none&#8221; animation_repeat__hover=&#8221;once&#8221; animation_repeat__hover_enabled=&#8221;once&#8221; animation_direction__hover=&#8221;center&#8221; animation_direction__hover_enabled=&#8221;center&#8221; animation_duration__hover=&#8221;1000ms&#8221; animation_duration__hover_enabled=&#8221;1000ms&#8221; animation_delay__hover=&#8221;0ms&#8221; animation_delay__hover_enabled=&#8221;0ms&#8221; animation_intensity_slide__hover=&#8221;50%&#8221; animation_intensity_slide__hover_enabled=&#8221;50%&#8221; animation_intensity_zoom__hover=&#8221;50%&#8221; animation_intensity_zoom__hover_enabled=&#8221;50%&#8221; animation_intensity_flip__hover=&#8221;50%&#8221; animation_intensity_flip__hover_enabled=&#8221;50%&#8221; animation_intensity_fold__hover=&#8221;50%&#8221; animation_intensity_fold__hover_enabled=&#8221;50%&#8221; animation_intensity_roll__hover=&#8221;50%&#8221; animation_intensity_roll__hover_enabled=&#8221;50%&#8221; animation_starting_opacity__hover=&#8221;0%&#8221; animation_starting_opacity__hover_enabled=&#8221;0%&#8221; animation_speed_curve__hover=&#8221;ease-in-out&#8221; animation_speed_curve__hover_enabled=&#8221;ease-in-out&#8221; hover_transition_duration__hover=&#8221;300ms&#8221; hover_transition_duration__hover_enabled=&#8221;300ms&#8221; hover_transition_delay__hover=&#8221;0ms&#8221; hover_transition_delay__hover_enabled=&#8221;0ms&#8221; hover_transition_speed_curve__hover=&#8221;ease&#8221; hover_transition_speed_curve__hover_enabled=&#8221;ease&#8221; background_color_gradient_stops__hover=&#8221;#2b87da 0%|#29c4a9 100%&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_text_color=&#8221;#000c24&#8243; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_text_color=&#8221;#000c24&#8243; header_font_size=&#8221;42px&#8221; header_2_font=&#8221;&#8211;et_global_body_font|700|||||||&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;24px&#8221; header_2_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_letter_spacing=&#8221;1px&#8221; header_3_line_height=&#8221;1.6em&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Chicago Crossroads 2025<\/strong><\/p>\n<h2>Engaging World Religions<\/h2>\n<p>Come and dive into what various religions teach, visit mosques, temples &amp; other places of worship, eat ethnic street food, and learn how to talk with people who don&#8217;t know Christ<\/p>\n<h2><strong>Thursdays June 19, 26, July 3, 10, &amp; 27<\/strong><br \/>5-9 pm<\/h2>\n<p>High school and college students (ages 15 \u2013 21)<br \/>$150 for the whole program.<\/p>\n<h2><strong>Lombard Gospel Chapel<\/strong><\/h2>\n<p>369 N. Stewart Ave., Lombard, IL 60148<\/p>\n<p><strong><\/strong><\/p>\n<p><span><\/span>For inquiries &amp; registration contact Kevin Schiltz 331-241-5282 <br \/><a href=\"mailto:Kevin.Schiltz@bethanyhouseil.org\">Kevin.Schiltz@bethanyhouseil.org<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;http:\/\/missionsencounter.com\/wp-content\/uploads\/2025\/04\/world-religions.jpg&#8221; title_text=&#8221;world-religions&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221; disabled_on=&#8221;on|on|on&#8221; disabled=&#8221;on&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_button button_url=&#8221;http:\/\/missionsencounter.com\/wp-content\/uploads\/2025\/04\/ChicagoCrossroads_small.pdf&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Download PDF&#8221; button_alignment=&#8221;center&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; custom_margin=&#8221;12px||30px||false|false&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; disabled=&#8221;on&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Monthly Meetings&#8221; _builder_version=&#8221;4.27.4&#8243; background_color=&#8221;rgba(201,141,54,0.36)&#8221; width=&#8221;72%&#8221; max_width=&#8221;80%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||25px||false|false&#8221; custom_padding=&#8221;9px|||||&#8221; custom_width_px__hover=&#8221;1080px&#8221; custom_width_px__hover_enabled=&#8221;1080px&#8221; custom_width_percent__hover=&#8221;80%&#8221; custom_width_percent__hover_enabled=&#8221;80%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; gutter_width__hover=&#8221;3&#8243; gutter_width__hover_enabled=&#8221;3&#8243; parallax_1__hover=&#8221;off&#8221; parallax_1__hover_enabled=&#8221;off&#8221; parallax_2__hover=&#8221;off&#8221; parallax_2__hover_enabled=&#8221;off&#8221; parallax_3__hover=&#8221;off&#8221; parallax_3__hover_enabled=&#8221;off&#8221; parallax_method_1__hover=&#8221;on&#8221; parallax_method_1__hover_enabled=&#8221;on&#8221; parallax_method_2__hover=&#8221;on&#8221; parallax_method_2__hover_enabled=&#8221;on&#8221; parallax_method_3__hover=&#8221;on&#8221; parallax_method_3__hover_enabled=&#8221;on&#8221; use_background_color_gradient__hover=&#8221;off&#8221; use_background_color_gradient__hover_enabled=&#8221;off&#8221; background_color_gradient_start__hover=&#8221;#2b87da&#8221; background_color_gradient_start__hover_enabled=&#8221;#2b87da&#8221; background_color_gradient_end__hover=&#8221;#29c4a9&#8243; background_color_gradient_end__hover_enabled=&#8221;#29c4a9&#8243; background_color_gradient_type__hover=&#8221;linear&#8221; background_color_gradient_type__hover_enabled=&#8221;linear&#8221; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_direction_radial__hover=&#8221;center&#8221; background_color_gradient_direction_radial__hover_enabled=&#8221;center&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; background_color_gradient_overlays_image__hover=&#8221;off&#8221; background_color_gradient_overlays_image__hover_enabled=&#8221;off&#8221; parallax__hover=&#8221;off&#8221; parallax__hover_enabled=&#8221;off&#8221; parallax_method__hover=&#8221;on&#8221; parallax_method__hover_enabled=&#8221;on&#8221; background_size__hover=&#8221;cover&#8221; background_size__hover_enabled=&#8221;cover&#8221; background_position__hover=&#8221;center&#8221; background_position__hover_enabled=&#8221;center&#8221; background_repeat__hover=&#8221;no-repeat&#8221; background_repeat__hover_enabled=&#8221;no-repeat&#8221; background_blend__hover=&#8221;normal&#8221; background_blend__hover_enabled=&#8221;normal&#8221; allow_player_pause__hover=&#8221;off&#8221; allow_player_pause__hover_enabled=&#8221;off&#8221; background_video_pause_outside_viewport__hover=&#8221;on&#8221; background_video_pause_outside_viewport__hover_enabled=&#8221;on&#8221; inner_shadow__hover=&#8221;off&#8221; inner_shadow__hover_enabled=&#8221;off&#8221; make_fullwidth__hover=&#8221;off&#8221; make_fullwidth__hover_enabled=&#8221;off&#8221; use_custom_width__hover=&#8221;off&#8221; use_custom_width__hover_enabled=&#8221;off&#8221; width_unit__hover=&#8221;on&#8221; width_unit__hover_enabled=&#8221;on&#8221; make_equal__hover=&#8221;off&#8221; make_equal__hover_enabled=&#8221;off&#8221; use_custom_gutter__hover=&#8221;off&#8221; use_custom_gutter__hover_enabled=&#8221;off&#8221; border_radii__hover=&#8221;on||||&#8221; border_radii__hover_enabled=&#8221;on||||&#8221; box_shadow_style__hover=&#8221;none&#8221; box_shadow_style__hover_enabled=&#8221;none&#8221; box_shadow_color__hover=&#8221;rgba(0,0,0,0.3)&#8221; box_shadow_color__hover_enabled=&#8221;rgba(0,0,0,0.3)&#8221; max_width__hover=&#8221;100%&#8221; max_width__hover_enabled=&#8221;100%&#8221; filter_hue_rotate__hover=&#8221;0deg&#8221; filter_hue_rotate__hover_enabled=&#8221;0deg&#8221; filter_saturate__hover=&#8221;100%&#8221; filter_saturate__hover_enabled=&#8221;100%&#8221; filter_brightness__hover=&#8221;100%&#8221; filter_brightness__hover_enabled=&#8221;100%&#8221; filter_contrast__hover=&#8221;100%&#8221; filter_contrast__hover_enabled=&#8221;100%&#8221; filter_invert__hover=&#8221;0%&#8221; filter_invert__hover_enabled=&#8221;0%&#8221; filter_sepia__hover=&#8221;0%&#8221; filter_sepia__hover_enabled=&#8221;0%&#8221; filter_opacity__hover=&#8221;100%&#8221; filter_opacity__hover_enabled=&#8221;100%&#8221; filter_blur__hover=&#8221;0px&#8221; filter_blur__hover_enabled=&#8221;0px&#8221; mix_blend_mode__hover=&#8221;normal&#8221; mix_blend_mode__hover_enabled=&#8221;normal&#8221; animation_style__hover=&#8221;none&#8221; animation_style__hover_enabled=&#8221;none&#8221; animation_repeat__hover=&#8221;once&#8221; animation_repeat__hover_enabled=&#8221;once&#8221; animation_direction__hover=&#8221;center&#8221; animation_direction__hover_enabled=&#8221;center&#8221; animation_duration__hover=&#8221;1000ms&#8221; animation_duration__hover_enabled=&#8221;1000ms&#8221; animation_delay__hover=&#8221;0ms&#8221; animation_delay__hover_enabled=&#8221;0ms&#8221; animation_intensity_slide__hover=&#8221;50%&#8221; animation_intensity_slide__hover_enabled=&#8221;50%&#8221; animation_intensity_zoom__hover=&#8221;50%&#8221; animation_intensity_zoom__hover_enabled=&#8221;50%&#8221; animation_intensity_flip__hover=&#8221;50%&#8221; animation_intensity_flip__hover_enabled=&#8221;50%&#8221; animation_intensity_fold__hover=&#8221;50%&#8221; animation_intensity_fold__hover_enabled=&#8221;50%&#8221; animation_intensity_roll__hover=&#8221;50%&#8221; animation_intensity_roll__hover_enabled=&#8221;50%&#8221; animation_starting_opacity__hover=&#8221;0%&#8221; animation_starting_opacity__hover_enabled=&#8221;0%&#8221; animation_speed_curve__hover=&#8221;ease-in-out&#8221; animation_speed_curve__hover_enabled=&#8221;ease-in-out&#8221; hover_transition_duration__hover=&#8221;300ms&#8221; hover_transition_duration__hover_enabled=&#8221;300ms&#8221; hover_transition_delay__hover=&#8221;0ms&#8221; hover_transition_delay__hover_enabled=&#8221;0ms&#8221; hover_transition_speed_curve__hover=&#8221;ease&#8221; hover_transition_speed_curve__hover_enabled=&#8221;ease&#8221; background_color_gradient_stops__hover=&#8221;#2b87da 0%|#29c4a9 100%&#8221;][et_pb_row _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#c98d36&#8243; width=&#8221;100%&#8221; max_width=&#8221;1490px&#8221; custom_margin=&#8221;-8px||||false|false&#8221; custom_padding=&#8221;15px||15px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;&#8211;et_global_body_font|700|||||||&#8221; header_text_align=&#8221;center&#8221; header_2_font=&#8221;&#8211;et_global_body_font|700|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;29px&#8221; custom_margin=&#8221;0px||-10px||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Schedule<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_5,1_5,1_5,1_5,1_5&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;2560px&#8221; custom_margin=&#8221;-5px|auto||auto||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; border_width_right=&#8221;2px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_orientation=&#8221;center&#8221; custom_padding=&#8221;|10px||10px|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Thursday, June 19<\/strong><\/p>\n<h3>Cosmic Drama: Story of the Bible<\/h3>\n<p><strong><\/strong><\/p>\n<ul>\n<li style=\"text-align: left;\"><strong>The Cosmic Drama<\/strong> (Kevin Schiltz)<\/li>\n<li style=\"text-align: left;\"><strong>The Bible and Religions<\/strong> (George Bristow)<\/li>\n<li style=\"text-align: left;\"><strong>Middle Eastern street food dinner<\/strong><\/li>\n<li style=\"text-align: left;\"><strong>Prayer walk local park<\/strong><\/li>\n<li style=\"text-align: left;\"><strong>Debrief and reflection<\/strong><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; border_width_right=&#8221;2px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_orientation=&#8221;center&#8221; custom_padding=&#8221;|10px||10px|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Thursday, June 26<\/strong><\/p>\n<h3>Islam<\/h3>\n<p><strong><\/strong><\/p>\n<ul>\n<li style=\"text-align: left;\"><strong>Islam<\/strong> (Kevin Schiltz)<\/li>\n<li style=\"text-align: left;\"><strong>Befriending Muslims<\/strong> (Luca Drago)<\/li>\n<li style=\"text-align: left;\"><strong>Shawerma dinner<\/strong><\/li>\n<li style=\"text-align: left;\"><strong>Mosque visit<\/strong><\/li>\n<li style=\"text-align: left;\"><strong>Debrief and reflection<\/strong><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; border_width_right=&#8221;2px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_orientation=&#8221;center&#8221; custom_padding=&#8221;|10px||10px|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Thursday, July 3<\/strong><\/p>\n<h3>Hinduism &amp; Hindus<\/h3>\n<p><strong><\/strong><\/p>\n<ul>\n<li style=\"text-align: left;\"><strong>From Hinduism to Christ<\/strong> (Girish Kumar)<\/li>\n<li style=\"text-align: left;\"><strong>Connecting with Hindus<\/strong> (Daniel Larimer)<\/li>\n<li style=\"text-align: left;\"><strong>Indian dinner<\/strong><\/li>\n<li style=\"text-align: left;\"><strong>Hindu temple tour<\/strong><\/li>\n<li style=\"text-align: left;\"><strong>Debrief and reflection<\/strong><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; border_width_right=&#8221;2px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_orientation=&#8221;center&#8221; custom_padding=&#8221;|10px||10px|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Thursday, July 10<\/strong><\/p>\n<h3>Muslims in the USA<\/h3>\n<p><strong><\/strong><\/p>\n<ul>\n<li style=\"text-align: left;\"><strong>Our Turkish Neighbors<\/strong> (Mike Urton)<\/li>\n<li style=\"text-align: left;\"><strong>Kebab dinner<\/strong><\/li>\n<li style=\"text-align: left;\"><strong>Turkish American Cultural Center<\/strong><\/li>\n<li style=\"text-align: left;\"><strong>Debrief and reflection<\/strong><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_orientation=&#8221;center&#8221; custom_padding=&#8221;|10px||10px|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Thursday, July 17<\/strong><\/p>\n<h3>Buddhism &amp; International Students<\/h3>\n<p><strong><\/strong><\/p>\n<ul>\n<li style=\"text-align: left;\"><strong>Buddhism in the USA<\/strong> (Jimmy Knepper)<\/li>\n<li style=\"text-align: left;\"><strong>International Students &amp; Missions<\/strong> (Nick Miller)<\/li>\n<li style=\"text-align: left;\"><strong>Vietnamese Ph\u1edf dinner<\/strong><\/li>\n<li style=\"text-align: left;\"><strong>Visit Buddhist temple<\/strong><\/li>\n<li style=\"text-align: left;\"><strong>Debrief and reflection<\/strong><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Monthly Meetings&#8221; _builder_version=&#8221;4.27.4&#8243; background_color=&#8221;#FFFFFF&#8221; width=&#8221;72%&#8221; max_width=&#8221;80%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;9px|||||&#8221; custom_width_px__hover=&#8221;1080px&#8221; custom_width_px__hover_enabled=&#8221;1080px&#8221; custom_width_percent__hover=&#8221;80%&#8221; custom_width_percent__hover_enabled=&#8221;80%&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; gutter_width__hover=&#8221;3&#8243; gutter_width__hover_enabled=&#8221;3&#8243; parallax_1__hover=&#8221;off&#8221; parallax_1__hover_enabled=&#8221;off&#8221; parallax_2__hover=&#8221;off&#8221; parallax_2__hover_enabled=&#8221;off&#8221; parallax_3__hover=&#8221;off&#8221; parallax_3__hover_enabled=&#8221;off&#8221; parallax_method_1__hover=&#8221;on&#8221; parallax_method_1__hover_enabled=&#8221;on&#8221; parallax_method_2__hover=&#8221;on&#8221; parallax_method_2__hover_enabled=&#8221;on&#8221; parallax_method_3__hover=&#8221;on&#8221; parallax_method_3__hover_enabled=&#8221;on&#8221; use_background_color_gradient__hover=&#8221;off&#8221; use_background_color_gradient__hover_enabled=&#8221;off&#8221; background_color_gradient_start__hover=&#8221;#2b87da&#8221; background_color_gradient_start__hover_enabled=&#8221;#2b87da&#8221; background_color_gradient_end__hover=&#8221;#29c4a9&#8243; background_color_gradient_end__hover_enabled=&#8221;#29c4a9&#8243; background_color_gradient_type__hover=&#8221;linear&#8221; background_color_gradient_type__hover_enabled=&#8221;linear&#8221; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_direction_radial__hover=&#8221;center&#8221; background_color_gradient_direction_radial__hover_enabled=&#8221;center&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; background_color_gradient_overlays_image__hover=&#8221;off&#8221; background_color_gradient_overlays_image__hover_enabled=&#8221;off&#8221; parallax__hover=&#8221;off&#8221; parallax__hover_enabled=&#8221;off&#8221; parallax_method__hover=&#8221;on&#8221; parallax_method__hover_enabled=&#8221;on&#8221; background_size__hover=&#8221;cover&#8221; background_size__hover_enabled=&#8221;cover&#8221; background_position__hover=&#8221;center&#8221; background_position__hover_enabled=&#8221;center&#8221; background_repeat__hover=&#8221;no-repeat&#8221; background_repeat__hover_enabled=&#8221;no-repeat&#8221; background_blend__hover=&#8221;normal&#8221; background_blend__hover_enabled=&#8221;normal&#8221; allow_player_pause__hover=&#8221;off&#8221; allow_player_pause__hover_enabled=&#8221;off&#8221; background_video_pause_outside_viewport__hover=&#8221;on&#8221; background_video_pause_outside_viewport__hover_enabled=&#8221;on&#8221; inner_shadow__hover=&#8221;off&#8221; inner_shadow__hover_enabled=&#8221;off&#8221; make_fullwidth__hover=&#8221;off&#8221; make_fullwidth__hover_enabled=&#8221;off&#8221; use_custom_width__hover=&#8221;off&#8221; use_custom_width__hover_enabled=&#8221;off&#8221; width_unit__hover=&#8221;on&#8221; width_unit__hover_enabled=&#8221;on&#8221; make_equal__hover=&#8221;off&#8221; make_equal__hover_enabled=&#8221;off&#8221; use_custom_gutter__hover=&#8221;off&#8221; use_custom_gutter__hover_enabled=&#8221;off&#8221; border_radii__hover=&#8221;on||||&#8221; border_radii__hover_enabled=&#8221;on||||&#8221; box_shadow_style__hover=&#8221;none&#8221; box_shadow_style__hover_enabled=&#8221;none&#8221; box_shadow_color__hover=&#8221;rgba(0,0,0,0.3)&#8221; box_shadow_color__hover_enabled=&#8221;rgba(0,0,0,0.3)&#8221; max_width__hover=&#8221;100%&#8221; max_width__hover_enabled=&#8221;100%&#8221; filter_hue_rotate__hover=&#8221;0deg&#8221; filter_hue_rotate__hover_enabled=&#8221;0deg&#8221; filter_saturate__hover=&#8221;100%&#8221; filter_saturate__hover_enabled=&#8221;100%&#8221; filter_brightness__hover=&#8221;100%&#8221; filter_brightness__hover_enabled=&#8221;100%&#8221; filter_contrast__hover=&#8221;100%&#8221; filter_contrast__hover_enabled=&#8221;100%&#8221; filter_invert__hover=&#8221;0%&#8221; filter_invert__hover_enabled=&#8221;0%&#8221; filter_sepia__hover=&#8221;0%&#8221; filter_sepia__hover_enabled=&#8221;0%&#8221; filter_opacity__hover=&#8221;100%&#8221; filter_opacity__hover_enabled=&#8221;100%&#8221; filter_blur__hover=&#8221;0px&#8221; filter_blur__hover_enabled=&#8221;0px&#8221; mix_blend_mode__hover=&#8221;normal&#8221; mix_blend_mode__hover_enabled=&#8221;normal&#8221; animation_style__hover=&#8221;none&#8221; animation_style__hover_enabled=&#8221;none&#8221; animation_repeat__hover=&#8221;once&#8221; animation_repeat__hover_enabled=&#8221;once&#8221; animation_direction__hover=&#8221;center&#8221; animation_direction__hover_enabled=&#8221;center&#8221; animation_duration__hover=&#8221;1000ms&#8221; animation_duration__hover_enabled=&#8221;1000ms&#8221; animation_delay__hover=&#8221;0ms&#8221; animation_delay__hover_enabled=&#8221;0ms&#8221; animation_intensity_slide__hover=&#8221;50%&#8221; animation_intensity_slide__hover_enabled=&#8221;50%&#8221; animation_intensity_zoom__hover=&#8221;50%&#8221; animation_intensity_zoom__hover_enabled=&#8221;50%&#8221; animation_intensity_flip__hover=&#8221;50%&#8221; animation_intensity_flip__hover_enabled=&#8221;50%&#8221; animation_intensity_fold__hover=&#8221;50%&#8221; animation_intensity_fold__hover_enabled=&#8221;50%&#8221; animation_intensity_roll__hover=&#8221;50%&#8221; animation_intensity_roll__hover_enabled=&#8221;50%&#8221; animation_starting_opacity__hover=&#8221;0%&#8221; animation_starting_opacity__hover_enabled=&#8221;0%&#8221; animation_speed_curve__hover=&#8221;ease-in-out&#8221; animation_speed_curve__hover_enabled=&#8221;ease-in-out&#8221; hover_transition_duration__hover=&#8221;300ms&#8221; hover_transition_duration__hover_enabled=&#8221;300ms&#8221; hover_transition_delay__hover=&#8221;0ms&#8221; hover_transition_delay__hover_enabled=&#8221;0ms&#8221; hover_transition_speed_curve__hover=&#8221;ease&#8221; hover_transition_speed_curve__hover_enabled=&#8221;ease&#8221; background_color_gradient_stops__hover=&#8221;#2b87da 0%|#29c4a9 100%&#8221;][et_pb_row _builder_version=&#8221;4.18.0&#8243; border_width_right=&#8221;2px&#8221; border_color_right=&#8221;#FFFFFF&#8221; custom_width_px__hover=&#8221;1080px&#8221; custom_width_px__hover_enabled=&#8221;1080px&#8221; custom_width_percent__hover=&#8221;80%&#8221; custom_width_percent__hover_enabled=&#8221;80%&#8221; global_colors_info=&#8221;{}&#8221; use_custom_width__hover=&#8221;off&#8221; use_custom_width__hover_enabled=&#8221;off&#8221; width_unit__hover=&#8221;on&#8221; width_unit__hover_enabled=&#8221;on&#8221; gutter_width__hover=&#8221;3&#8243; gutter_width__hover_enabled=&#8221;3&#8243; parallax_1__hover=&#8221;off&#8221; parallax_1__hover_enabled=&#8221;off&#8221; parallax_2__hover=&#8221;off&#8221; parallax_2__hover_enabled=&#8221;off&#8221; parallax_3__hover=&#8221;off&#8221; parallax_3__hover_enabled=&#8221;off&#8221; parallax_4__hover=&#8221;off&#8221; parallax_4__hover_enabled=&#8221;off&#8221; parallax_5__hover=&#8221;off&#8221; parallax_5__hover_enabled=&#8221;off&#8221; parallax_6__hover=&#8221;off&#8221; parallax_6__hover_enabled=&#8221;off&#8221; parallax_method_1__hover=&#8221;on&#8221; parallax_method_1__hover_enabled=&#8221;on&#8221; parallax_method_2__hover=&#8221;on&#8221; parallax_method_2__hover_enabled=&#8221;on&#8221; parallax_method_3__hover=&#8221;on&#8221; parallax_method_3__hover_enabled=&#8221;on&#8221; parallax_method_4__hover=&#8221;on&#8221; parallax_method_4__hover_enabled=&#8221;on&#8221; parallax_method_5__hover=&#8221;on&#8221; parallax_method_5__hover_enabled=&#8221;on&#8221; parallax_method_6__hover=&#8221;on&#8221; parallax_method_6__hover_enabled=&#8221;on&#8221; use_background_color_gradient__hover=&#8221;off&#8221; use_background_color_gradient__hover_enabled=&#8221;off&#8221; background_color_gradient_start__hover=&#8221;#2b87da&#8221; background_color_gradient_start__hover_enabled=&#8221;#2b87da&#8221; background_color_gradient_end__hover=&#8221;#29c4a9&#8243; background_color_gradient_end__hover_enabled=&#8221;#29c4a9&#8243; background_color_gradient_type__hover=&#8221;linear&#8221; background_color_gradient_type__hover_enabled=&#8221;linear&#8221; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_direction_radial__hover=&#8221;center&#8221; background_color_gradient_direction_radial__hover_enabled=&#8221;center&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; background_color_gradient_overlays_image__hover=&#8221;off&#8221; background_color_gradient_overlays_image__hover_enabled=&#8221;off&#8221; parallax__hover=&#8221;off&#8221; parallax__hover_enabled=&#8221;off&#8221; parallax_method__hover=&#8221;on&#8221; parallax_method__hover_enabled=&#8221;on&#8221; background_size__hover=&#8221;cover&#8221; background_size__hover_enabled=&#8221;cover&#8221; background_position__hover=&#8221;center&#8221; background_position__hover_enabled=&#8221;center&#8221; background_repeat__hover=&#8221;no-repeat&#8221; background_repeat__hover_enabled=&#8221;no-repeat&#8221; background_blend__hover=&#8221;normal&#8221; background_blend__hover_enabled=&#8221;normal&#8221; allow_player_pause__hover=&#8221;off&#8221; allow_player_pause__hover_enabled=&#8221;off&#8221; background_video_pause_outside_viewport__hover=&#8221;on&#8221; background_video_pause_outside_viewport__hover_enabled=&#8221;on&#8221; make_fullwidth__hover=&#8221;off&#8221; make_fullwidth__hover_enabled=&#8221;off&#8221; use_custom_gutter__hover=&#8221;off&#8221; use_custom_gutter__hover_enabled=&#8221;off&#8221; make_equal__hover=&#8221;off&#8221; make_equal__hover_enabled=&#8221;off&#8221; border_radii__hover=&#8221;on||||&#8221; border_radii__hover_enabled=&#8221;on||||&#8221; box_shadow_style__hover=&#8221;none&#8221; box_shadow_style__hover_enabled=&#8221;none&#8221; box_shadow_color__hover=&#8221;rgba(0,0,0,0.3)&#8221; box_shadow_color__hover_enabled=&#8221;rgba(0,0,0,0.3)&#8221; filter_hue_rotate__hover=&#8221;0deg&#8221; filter_hue_rotate__hover_enabled=&#8221;0deg&#8221; filter_saturate__hover=&#8221;100%&#8221; filter_saturate__hover_enabled=&#8221;100%&#8221; filter_brightness__hover=&#8221;100%&#8221; filter_brightness__hover_enabled=&#8221;100%&#8221; filter_contrast__hover=&#8221;100%&#8221; filter_contrast__hover_enabled=&#8221;100%&#8221; filter_invert__hover=&#8221;0%&#8221; filter_invert__hover_enabled=&#8221;0%&#8221; filter_sepia__hover=&#8221;0%&#8221; filter_sepia__hover_enabled=&#8221;0%&#8221; filter_opacity__hover=&#8221;100%&#8221; filter_opacity__hover_enabled=&#8221;100%&#8221; filter_blur__hover=&#8221;0px&#8221; filter_blur__hover_enabled=&#8221;0px&#8221; mix_blend_mode__hover=&#8221;normal&#8221; mix_blend_mode__hover_enabled=&#8221;normal&#8221; animation_style__hover=&#8221;none&#8221; animation_style__hover_enabled=&#8221;none&#8221; animation_repeat__hover=&#8221;once&#8221; animation_repeat__hover_enabled=&#8221;once&#8221; animation_direction__hover=&#8221;center&#8221; animation_direction__hover_enabled=&#8221;center&#8221; animation_duration__hover=&#8221;1000ms&#8221; animation_duration__hover_enabled=&#8221;1000ms&#8221; animation_delay__hover=&#8221;0ms&#8221; animation_delay__hover_enabled=&#8221;0ms&#8221; animation_intensity_slide__hover=&#8221;50%&#8221; animation_intensity_slide__hover_enabled=&#8221;50%&#8221; animation_intensity_zoom__hover=&#8221;50%&#8221; animation_intensity_zoom__hover_enabled=&#8221;50%&#8221; animation_intensity_flip__hover=&#8221;50%&#8221; animation_intensity_flip__hover_enabled=&#8221;50%&#8221; animation_intensity_fold__hover=&#8221;50%&#8221; animation_intensity_fold__hover_enabled=&#8221;50%&#8221; animation_intensity_roll__hover=&#8221;50%&#8221; animation_intensity_roll__hover_enabled=&#8221;50%&#8221; animation_starting_opacity__hover=&#8221;0%&#8221; animation_starting_opacity__hover_enabled=&#8221;0%&#8221; animation_speed_curve__hover=&#8221;ease-in-out&#8221; animation_speed_curve__hover_enabled=&#8221;ease-in-out&#8221; hover_transition_duration__hover=&#8221;300ms&#8221; hover_transition_duration__hover_enabled=&#8221;300ms&#8221; hover_transition_delay__hover=&#8221;0ms&#8221; hover_transition_delay__hover_enabled=&#8221;0ms&#8221; hover_transition_speed_curve__hover=&#8221;ease&#8221; hover_transition_speed_curve__hover_enabled=&#8221;ease&#8221; background_color_gradient_stops__hover=&#8221;#2b87da 0%|#29c4a9 100%&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;35px||||false|false&#8221; custom_padding=&#8221;||23px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Inquiries \/ Registration<\/h2>\n<p>Fill out the form below if you have any questions or would like to register.<\/p>\n<p>[\/et_pb_text][et_pb_contact_form use_spam_service=&#8221;on&#8221; recaptcha_list=&#8221;Default-0&#8243; email=&#8221;info@missionsencounter.com, schiltz@fastmail.fm&#8221; custom_message=&#8221;Chicago Crossroads Inquiries\/Registration||et_pb_line_break_holder||First Name: %%First_Name%%||et_pb_line_break_holder||Last Name: %%Last_Name%%||et_pb_line_break_holder||Email: %%Email%%||et_pb_line_break_holder||Home Church: %%Assembly%%||et_pb_line_break_holder||Questions: %%Questions%%&#8221; success_message=&#8221;Thank you. We will get back to you shortly with more information&#8221; submit_button_text=&#8221;Send&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; _unique_id=&#8221;28941dd3-30b3-4fcf-b5d5-ca84e6f1d7e5&#8243; background_color=&#8221;RGBA(255,255,255,0)&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#0C71C3&#8243; button_icon=&#8221;&#xf054;||fa||900&#8243; button_custom_padding=&#8221;|50px||50px|false|false&#8221; width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;-33px|||||&#8221; custom_padding=&#8221;0px|||||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_contact_field field_id=&#8221;First_Name&#8221; field_title=&#8221;First Name&#8221; _builder_version=&#8221;4.25.1&#8243; form_field_background_color=&#8221;rgba(127,114,80,0.1)&#8221; form_field_text_color=&#8221;#000000&#8243; background_enable_color=&#8221;off&#8221; width=&#8221;80%&#8221; max_width=&#8221;80%&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Last_Name&#8221; field_title=&#8221;Last Name&#8221; _builder_version=&#8221;4.25.1&#8243; form_field_background_color=&#8221;rgba(127,114,80,0.1)&#8221; form_field_text_color=&#8221;#000000&#8243; background_enable_color=&#8221;off&#8221; width=&#8221;80%&#8221; max_width=&#8221;80%&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Email&#8221; field_title=&#8221;Email&#8221; field_type=&#8221;email&#8221; _builder_version=&#8221;4.25.1&#8243; form_field_background_color=&#8221;rgba(127,114,80,0.1)&#8221; form_field_text_color=&#8221;#000000&#8243; width=&#8221;80%&#8221; max_width=&#8221;80%&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Assembly&#8221; field_title=&#8221;Home Church&#8221; required_mark=&#8221;off&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; form_field_background_color=&#8221;rgba(127,114,80,0.1)&#8221; form_field_text_color=&#8221;#000000&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Questions&#8221; field_title=&#8221;Questions&#8221; required_mark=&#8221;off&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; form_field_background_color=&#8221;rgba(127,114,80,0.1)&#8221; form_field_text_color=&#8221;#000000&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; admin_label=&#8221;Scholarships&#8221; _builder_version=&#8221;4.25.1&#8243; background_color=&#8221;rgba(7,100,194,0.2)&#8221; custom_padding=&#8221;0|10vw|||false|false&#8221; custom_padding_tablet=&#8221;|10vw||10vw||true&#8221; custom_padding_phone=&#8221;&#8221; custom_width_px__hover=&#8221;1080px&#8221; custom_width_px__hover_enabled=&#8221;1080px&#8221; custom_width_percent__hover=&#8221;80%&#8221; custom_width_percent__hover_enabled=&#8221;80%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; gutter_width__hover=&#8221;3&#8243; gutter_width__hover_enabled=&#8221;3&#8243; parallax_1__hover=&#8221;off&#8221; parallax_1__hover_enabled=&#8221;off&#8221; parallax_2__hover=&#8221;off&#8221; parallax_2__hover_enabled=&#8221;off&#8221; parallax_3__hover=&#8221;off&#8221; parallax_3__hover_enabled=&#8221;off&#8221; parallax_method_1__hover=&#8221;on&#8221; parallax_method_1__hover_enabled=&#8221;on&#8221; parallax_method_2__hover=&#8221;on&#8221; parallax_method_2__hover_enabled=&#8221;on&#8221; parallax_method_3__hover=&#8221;on&#8221; parallax_method_3__hover_enabled=&#8221;on&#8221; use_background_color_gradient__hover=&#8221;off&#8221; use_background_color_gradient__hover_enabled=&#8221;off&#8221; background_color_gradient_start__hover=&#8221;#2b87da&#8221; background_color_gradient_start__hover_enabled=&#8221;#2b87da&#8221; background_color_gradient_end__hover=&#8221;#29c4a9&#8243; background_color_gradient_end__hover_enabled=&#8221;#29c4a9&#8243; background_color_gradient_type__hover=&#8221;linear&#8221; background_color_gradient_type__hover_enabled=&#8221;linear&#8221; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_direction_radial__hover=&#8221;center&#8221; background_color_gradient_direction_radial__hover_enabled=&#8221;center&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; background_color_gradient_overlays_image__hover=&#8221;off&#8221; background_color_gradient_overlays_image__hover_enabled=&#8221;off&#8221; parallax__hover=&#8221;off&#8221; parallax__hover_enabled=&#8221;off&#8221; parallax_method__hover=&#8221;on&#8221; parallax_method__hover_enabled=&#8221;on&#8221; background_size__hover=&#8221;cover&#8221; background_size__hover_enabled=&#8221;cover&#8221; background_position__hover=&#8221;center&#8221; background_position__hover_enabled=&#8221;center&#8221; background_repeat__hover=&#8221;no-repeat&#8221; background_repeat__hover_enabled=&#8221;no-repeat&#8221; background_blend__hover=&#8221;normal&#8221; background_blend__hover_enabled=&#8221;normal&#8221; allow_player_pause__hover=&#8221;off&#8221; allow_player_pause__hover_enabled=&#8221;off&#8221; background_video_pause_outside_viewport__hover=&#8221;on&#8221; background_video_pause_outside_viewport__hover_enabled=&#8221;on&#8221; inner_shadow__hover=&#8221;off&#8221; inner_shadow__hover_enabled=&#8221;off&#8221; make_fullwidth__hover=&#8221;off&#8221; make_fullwidth__hover_enabled=&#8221;off&#8221; use_custom_width__hover=&#8221;off&#8221; use_custom_width__hover_enabled=&#8221;off&#8221; width_unit__hover=&#8221;on&#8221; width_unit__hover_enabled=&#8221;on&#8221; make_equal__hover=&#8221;off&#8221; make_equal__hover_enabled=&#8221;off&#8221; use_custom_gutter__hover=&#8221;off&#8221; use_custom_gutter__hover_enabled=&#8221;off&#8221; border_radii__hover=&#8221;on||||&#8221; border_radii__hover_enabled=&#8221;on||||&#8221; box_shadow_style__hover=&#8221;none&#8221; box_shadow_style__hover_enabled=&#8221;none&#8221; box_shadow_color__hover=&#8221;rgba(0,0,0,0.3)&#8221; box_shadow_color__hover_enabled=&#8221;rgba(0,0,0,0.3)&#8221; max_width__hover=&#8221;100%&#8221; max_width__hover_enabled=&#8221;100%&#8221; filter_hue_rotate__hover=&#8221;0deg&#8221; filter_hue_rotate__hover_enabled=&#8221;0deg&#8221; filter_saturate__hover=&#8221;100%&#8221; filter_saturate__hover_enabled=&#8221;100%&#8221; filter_brightness__hover=&#8221;100%&#8221; filter_brightness__hover_enabled=&#8221;100%&#8221; filter_contrast__hover=&#8221;100%&#8221; filter_contrast__hover_enabled=&#8221;100%&#8221; filter_invert__hover=&#8221;0%&#8221; filter_invert__hover_enabled=&#8221;0%&#8221; filter_sepia__hover=&#8221;0%&#8221; filter_sepia__hover_enabled=&#8221;0%&#8221; filter_opacity__hover=&#8221;100%&#8221; filter_opacity__hover_enabled=&#8221;100%&#8221; filter_blur__hover=&#8221;0px&#8221; filter_blur__hover_enabled=&#8221;0px&#8221; mix_blend_mode__hover=&#8221;normal&#8221; mix_blend_mode__hover_enabled=&#8221;normal&#8221; animation_style__hover=&#8221;none&#8221; animation_style__hover_enabled=&#8221;none&#8221; animation_repeat__hover=&#8221;once&#8221; animation_repeat__hover_enabled=&#8221;once&#8221; animation_direction__hover=&#8221;center&#8221; animation_direction__hover_enabled=&#8221;center&#8221; animation_duration__hover=&#8221;1000ms&#8221; animation_duration__hover_enabled=&#8221;1000ms&#8221; animation_delay__hover=&#8221;0ms&#8221; animation_delay__hover_enabled=&#8221;0ms&#8221; animation_intensity_slide__hover=&#8221;50%&#8221; animation_intensity_slide__hover_enabled=&#8221;50%&#8221; animation_intensity_zoom__hover=&#8221;50%&#8221; animation_intensity_zoom__hover_enabled=&#8221;50%&#8221; animation_intensity_flip__hover=&#8221;50%&#8221; animation_intensity_flip__hover_enabled=&#8221;50%&#8221; animation_intensity_fold__hover=&#8221;50%&#8221; animation_intensity_fold__hover_enabled=&#8221;50%&#8221; animation_intensity_roll__hover=&#8221;50%&#8221; animation_intensity_roll__hover_enabled=&#8221;50%&#8221; animation_starting_opacity__hover=&#8221;0%&#8221; animation_starting_opacity__hover_enabled=&#8221;0%&#8221; animation_speed_curve__hover=&#8221;ease-in-out&#8221; animation_speed_curve__hover_enabled=&#8221;ease-in-out&#8221; hover_transition_duration__hover=&#8221;300ms&#8221; hover_transition_duration__hover_enabled=&#8221;300ms&#8221; hover_transition_delay__hover=&#8221;0ms&#8221; hover_transition_delay__hover_enabled=&#8221;0ms&#8221; hover_transition_speed_curve__hover=&#8221;ease&#8221; hover_transition_speed_curve__hover_enabled=&#8221;ease&#8221; background_color_gradient_stops__hover=&#8221;#2b87da 0%|#29c4a9 100%&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; make_equal=&#8221;on&#8221; padding_top_bottom_link_2=&#8221;false&#8221; _builder_version=&#8221;4.18.0&#8243; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; module_alignment=&#8221;right&#8221; custom_padding=&#8221;0|0px|25px|0px|false|false&#8221; custom_css_main_element=&#8221;margin: auto;&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.18.0&#8243; custom_padding=&#8221;|||&#8221; custom_padding_tablet=&#8221;|10vw||10vw||true&#8221; custom_padding_phone=&#8221;|||&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221; padding_phone=&#8221;|||&#8221; padding_tablet=&#8221;|10vw||10vw||true&#8221; padding_last_edited=&#8221;off|desktop&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.18.0&#8243; background_image=&#8221;http:\/\/missionsencounter.com\/wp-content\/uploads\/2022\/10\/environmental-nonprofit-35.jpg&#8221; parallax=&#8221;on&#8221; custom_margin=&#8221;||&#8221; custom_padding=&#8221;16vw||16vw||true&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;8vw|||&#8221; custom_padding_tablet=&#8221;0vw|||&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221; padding_tablet=&#8221;0vw|||&#8221; padding_last_edited=&#8221;off|desktop&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; text_line_height=&#8221;2em&#8221; header_2_font=&#8221;||||||||&#8221; header_2_text_color=&#8221;#000c24&#8243; header_2_font_size=&#8221;32px&#8221; header_2_line_height=&#8221;2em&#8221; max_width=&#8221;800px&#8221; text_font_size_tablet=&#8221;14px&#8221; text_font_size_phone=&#8221;&#8221; text_font_size_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Short-term Mission Scholarships<\/h2>\n<p>We offer short-term mission scholarships to young people to encourage their support and pursuit of missions.<\/p>\n<p>Candidates will show an interest in attending the Missions Encounter meetings to grow in their knowledge of the missionary experience and learn about how the Lord is working through His people around the world.<\/p>\n<p>After completing their trip, they will be given some time at a Missions Encounter meeting to make a brief presentation.<\/p>\n<p>Interested candidates should attend a Missions Encounter Study Class and talk to an assembly rep to get the application process started.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Youth Engaged in Missions &nbsp;Chicago Crossroads 2025 Engaging World Religions Come and dive into what various religions teach, visit mosques, temples &amp; other places of worship, eat ethnic street food, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"ppma_author":[15],"class_list":["post-750","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Youth Engaged in Missions Chicago Crossroads 2025 Engaging World Religions Come and dive into what various religions teach, visit mosques, temples &amp; other places of worship, eat ethnic street food, and learn how to talk with people who don\u2019t know Christ Thursdays June 19, 26, July 3, 10, &amp; 275-9 pm High school and\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/missionsencounter.com\/index.php\/missions-encounter-youth\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Chicago Missionary Study Class - Just another WordPress site\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Missions Encounter Youth - Chicago Missionary Study Class\" \/>\n\t\t<meta property=\"og:description\" content=\"Youth Engaged in Missions Chicago Crossroads 2025 Engaging World Religions Come and dive into what various religions teach, visit mosques, temples &amp; other places of worship, eat ethnic street food, and learn how to talk with people who don\u2019t know Christ Thursdays June 19, 26, July 3, 10, &amp; 275-9 pm High school and\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/missionsencounter.com\/index.php\/missions-encounter-youth\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-05-31T15:37:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-03-24T21:41:30+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Missions Encounter Youth - Chicago Missionary Study Class\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Youth Engaged in Missions Chicago Crossroads 2025 Engaging World Religions Come and dive into what various religions teach, visit mosques, temples &amp; other places of worship, eat ethnic street food, and learn how to talk with people who don\u2019t know Christ Thursdays June 19, 26, July 3, 10, &amp; 275-9 pm High school and\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/missionsencounter.com\\\/index.php\\\/missions-encounter-youth\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/missionsencounter.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/missionsencounter.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/missionsencounter.com\\\/index.php\\\/missions-encounter-youth\\\/#listItem\",\"name\":\"Missions Encounter Youth\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/missionsencounter.com\\\/index.php\\\/missions-encounter-youth\\\/#listItem\",\"position\":2,\"name\":\"Missions Encounter Youth\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/missionsencounter.com#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/missionsencounter.com\\\/#organization\",\"name\":\"Chicago Missionary Study Class\",\"description\":\"Just another WordPress site\",\"url\":\"https:\\\/\\\/missionsencounter.com\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/missionsencounter.com\\\/index.php\\\/missions-encounter-youth\\\/#webpage\",\"url\":\"https:\\\/\\\/missionsencounter.com\\\/index.php\\\/missions-encounter-youth\\\/\",\"name\":\"Missions Encounter Youth - Chicago Missionary Study Class\",\"description\":\"Youth Engaged in Missions Chicago Crossroads 2025 Engaging World Religions Come and dive into what various religions teach, visit mosques, temples & other places of worship, eat ethnic street food, and learn how to talk with people who don\\u2019t know Christ Thursdays June 19, 26, July 3, 10, & 275-9 pm High school and\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/missionsencounter.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/missionsencounter.com\\\/index.php\\\/missions-encounter-youth\\\/#breadcrumblist\"},\"datePublished\":\"2024-05-31T15:37:01+00:00\",\"dateModified\":\"2026-03-24T21:41:30+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/missionsencounter.com\\\/#website\",\"url\":\"https:\\\/\\\/missionsencounter.com\\\/\",\"name\":\"Chicago Missionary Study Class\",\"description\":\"Just another WordPress site\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/missionsencounter.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Missions Encounter Youth - Chicago Missionary Study Class","description":"Youth Engaged in Missions Chicago Crossroads 2025 Engaging World Religions Come and dive into what various religions teach, visit mosques, temples & other places of worship, eat ethnic street food, and learn how to talk with people who don\u2019t know Christ Thursdays June 19, 26, July 3, 10, & 275-9 pm High school and","canonical_url":"https:\/\/missionsencounter.com\/index.php\/missions-encounter-youth\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/missionsencounter.com\/index.php\/missions-encounter-youth\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/missionsencounter.com#listItem","position":1,"name":"Home","item":"https:\/\/missionsencounter.com","nextItem":{"@type":"ListItem","@id":"https:\/\/missionsencounter.com\/index.php\/missions-encounter-youth\/#listItem","name":"Missions Encounter Youth"}},{"@type":"ListItem","@id":"https:\/\/missionsencounter.com\/index.php\/missions-encounter-youth\/#listItem","position":2,"name":"Missions Encounter Youth","previousItem":{"@type":"ListItem","@id":"https:\/\/missionsencounter.com#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/missionsencounter.com\/#organization","name":"Chicago Missionary Study Class","description":"Just another WordPress site","url":"https:\/\/missionsencounter.com\/"},{"@type":"WebPage","@id":"https:\/\/missionsencounter.com\/index.php\/missions-encounter-youth\/#webpage","url":"https:\/\/missionsencounter.com\/index.php\/missions-encounter-youth\/","name":"Missions Encounter Youth - Chicago Missionary Study Class","description":"Youth Engaged in Missions Chicago Crossroads 2025 Engaging World Religions Come and dive into what various religions teach, visit mosques, temples & other places of worship, eat ethnic street food, and learn how to talk with people who don\u2019t know Christ Thursdays June 19, 26, July 3, 10, & 275-9 pm High school and","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/missionsencounter.com\/#website"},"breadcrumb":{"@id":"https:\/\/missionsencounter.com\/index.php\/missions-encounter-youth\/#breadcrumblist"},"datePublished":"2024-05-31T15:37:01+00:00","dateModified":"2026-03-24T21:41:30+00:00"},{"@type":"WebSite","@id":"https:\/\/missionsencounter.com\/#website","url":"https:\/\/missionsencounter.com\/","name":"Chicago Missionary Study Class","description":"Just another WordPress site","inLanguage":"en-US","publisher":{"@id":"https:\/\/missionsencounter.com\/#organization"}}]},"og:locale":"en_US","og:site_name":"Chicago Missionary Study Class - Just another WordPress site","og:type":"article","og:title":"Missions Encounter Youth - Chicago Missionary Study Class","og:description":"Youth Engaged in Missions Chicago Crossroads 2025 Engaging World Religions Come and dive into what various religions teach, visit mosques, temples &amp; other places of worship, eat ethnic street food, and learn how to talk with people who don\u2019t know Christ Thursdays June 19, 26, July 3, 10, &amp; 275-9 pm High school and","og:url":"https:\/\/missionsencounter.com\/index.php\/missions-encounter-youth\/","article:published_time":"2024-05-31T15:37:01+00:00","article:modified_time":"2026-03-24T21:41:30+00:00","twitter:card":"summary_large_image","twitter:title":"Missions Encounter Youth - Chicago Missionary Study Class","twitter:description":"Youth Engaged in Missions Chicago Crossroads 2025 Engaging World Religions Come and dive into what various religions teach, visit mosques, temples &amp; other places of worship, eat ethnic street food, and learn how to talk with people who don\u2019t know Christ Thursdays June 19, 26, July 3, 10, &amp; 275-9 pm High school and"},"aioseo_meta_data":{"post_id":"750","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2024-05-31 15:33:53","updated":"2026-03-25 00:15:54","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/missionsencounter.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMissions Encounter Youth\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/missionsencounter.com"},{"label":"Missions Encounter Youth","link":"https:\/\/missionsencounter.com\/index.php\/missions-encounter-youth\/"}],"_links":{"self":[{"href":"https:\/\/missionsencounter.com\/index.php\/wp-json\/wp\/v2\/pages\/750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/missionsencounter.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/missionsencounter.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/missionsencounter.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/missionsencounter.com\/index.php\/wp-json\/wp\/v2\/comments?post=750"}],"version-history":[{"count":18,"href":"https:\/\/missionsencounter.com\/index.php\/wp-json\/wp\/v2\/pages\/750\/revisions"}],"predecessor-version":[{"id":1180,"href":"https:\/\/missionsencounter.com\/index.php\/wp-json\/wp\/v2\/pages\/750\/revisions\/1180"}],"wp:attachment":[{"href":"https:\/\/missionsencounter.com\/index.php\/wp-json\/wp\/v2\/media?parent=750"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/missionsencounter.com\/index.php\/wp-json\/wp\/v2\/ppma_author?post=750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}